{"id":2478,"date":"2021-03-17T15:50:26","date_gmt":"2021-03-17T15:50:26","guid":{"rendered":"https:\/\/oferplan.abc.es\/blog\/?p=2478"},"modified":"2024-05-30T06:44:39","modified_gmt":"2024-05-30T06:44:39","slug":"dia-del-padre","status":"publish","type":"post","link":"\/blog\/teatro\/dia-del-padre\/","title":{"rendered":"Obras de teatro para el d\u00eda del Padre 2021"},"content":{"rendered":"<p>Buscar <strong>obras de teatro para el d\u00eda del Padre de este 2021<\/strong> es muy buena manera de celebrarlo. En un momento en el que siguen activas muchas restricciones, el teatro ha demostrado que la cultura es segura, permitiendo disfrutar de un rato de ocio con todas las medidas de seguridad.<\/p>\n<p>A\u00f1adi\u00e9ndole que el pr\u00f3ximo 19 de marzo es festivo en la Comunidad de Madrid, hemos buscado en la <a href=\"https:\/\/oferplan.abc.es\/blog\/teatro\/cartelera-teatro-madrid\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>cartelera de teatro<\/strong><\/a> las obras m\u00e1s interesantes para celebrar el D\u00eda de San Jos\u00e9.<\/p>\n<p>Una manera divertida y emocionante de disfrutar del teatro de la capital en un festivo, pudiendo encontrar adem\u00e1s muchas promociones y descuentos con Oferplan para que, adem\u00e1s, sea m\u00e1s econ\u00f3mico que nunca.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-2512 size-large\" title=\"D\u00eda del Padre teatro\" src=\"https:\/\/oferplan.abc.es\/blog\/wp-content\/uploads\/sites\/10\/2021\/03\/dia-del-padre-teatro-1024x674.jpg\" alt=\"Celebra el D\u00eda del Padre en las butacas de un teatro\" width=\"629\" height=\"414\" \/><\/p>\n<h2><a href=\"https:\/\/oferplan.abc.es\/ofertas-descuentos\/entradas-importancia-llamarse-ernesto-madrid-7753.html?utm_source=blog&amp;utm_medium=lacolmena&amp;utm_campaign=diapadre\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>La importancia de llamarse Ernesto en el Teatro Lara<\/strong><\/a><\/h2>\n<p><strong>Oscar Wilde<\/strong> es uno de los dramaturgos m\u00e1s importantes del mundo y ahora tenemos la oportunidad de ver una de sus mejores <strong>obras de teatro en Madrid<\/strong>. <strong>La importancia de llamarse Ernesto<\/strong>, producida por <strong>PASOAZOR\u00cdN Teatro<\/strong>, es una versi\u00f3n ligeramente actualizada del cl\u00e1sico brit\u00e1nico pero manteniendo todos los detalles que le han convertido en una de las grandes obras de la literatura universal.<\/p>\n<p>En este caso, es <strong>Ram\u00f3n Paso<\/strong> el que ha realizado y dirigido la versi\u00f3n, a partir de una traducci\u00f3n de <strong>Sandra Pedraz Decker<\/strong>. A las \u00f3rdenes de paso se encuentran <strong>Ana Azor\u00edn<\/strong>, <strong>Sergio Otegui<\/strong>, <strong>In\u00e9s Kerzan<\/strong>, <strong>\u00c1ngela Peirat<\/strong>, <strong>Jordi Mill\u00e1n<\/strong>, <strong>Guillermo L\u00f3pez-Acosta<\/strong> y <strong>Paloma Paso Jardiel<\/strong>.<\/p>\n<p><strong>La importancia de llamarse Ernesto<\/strong> fue representada por primera vez en febrero de 1895 en Londres, donde el autor se revelaba ante la estricta moral victoriana. La obra, de hecho, satiriza sobre los convencionalismos sociales y apuesta por terminar con las expectativas precreadas y buscar la libertad m\u00e1s absoluta.<\/p>\n<p>No en vano, hay que recordar que <strong>Oscar Wilde<\/strong> fue encarcelado por vivir abiertamente su homosexualidad. Tambi\u00e9n esa historia vital explica la g\u00e9nesis de la obra. El autor considera que hay que ir un paso m\u00e1s adelante de lo que opinen los dem\u00e1s que es correcto o deseable, al menos si queremos ser felices con nosotros mismos.<\/p>\n<p>En la obra seguimos la vida de dos mujeres j\u00f3venes, Gwendolen y Cecily, que est\u00e1n enamoradas de Ernesto, un hombre ideal pero tambi\u00e9n inexistente que corresponde m\u00e1s bien a un arquetipo. En este lugar se colocan Jack y Algernon, enamorados de estas chicas y que intentar\u00e1n hacerles ver que son Ernesto para as\u00ed poder conquistarlas.<\/p>\n<p>Con Oferplan puedes comprar tu entrada por un 40% menos.<\/p>\n<p><strong>Direcci\u00f3n:<\/strong> <strong>Teatro Lara<\/strong>. Corredera Baja de San Pablo, 15, 28004 Madrid<\/p>\n<p><strong>Metro<\/strong>: Callao (L\u00edneas 3 y 5) y Santo Domingo (L\u00ednea 2)<\/p>\n<p><strong>Autob\u00fas<\/strong>: 001, 002 (gratuitos), 1, 2, 46, 74, 146, N16, N18, N19, N20, N21<\/p>\n<h2><a href=\"https:\/\/oferplan.abc.es\/ofertas-descuentos\/entradas-improvisa-tio-madrid-7811.html?utm_source=blog&amp;utm_medium=lacolmena&amp;utm_campaign=diapadre\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Improvisa T\u00edo en el Teatro Alfil<\/strong><\/a><\/h2>\n<p>Otra opci\u00f3n muy divertida para el <strong>d\u00eda del Padre 2021<\/strong> es acercarse al <strong>Teatro Alfil<\/strong> para descubrir su obra <strong>Improvisa T\u00edo<\/strong>.<\/p>\n<p>En este caso, permite hacer algo m\u00e1s divertido que simplemente ver una <strong>obra de teatro en Madrid<\/strong>, ya que se trata de un <strong>espect\u00e1culo de improvisaci\u00f3n en directo<\/strong>.<\/p>\n<p>De hecho, es en cierta forma como una especie de masterclass, ya que el p\u00fablico es un personaje m\u00e1s, teniendo que intervenir y dejarse llevar por las din\u00e1micas de improvisaci\u00f3n.<\/p>\n<p>No apto para padres t\u00edmidos, puede suponer una forma de celebrar el D\u00eda del Padre divertid\u00edsima para aquellos que les gusta re\u00edrse, ser el centro de atenci\u00f3n, improvisar y pasar un rato agradable con otras personas.<\/p>\n<p>Con una duraci\u00f3n aproximada de 80 minutos, el espect\u00e1culo lleva ya 10 temporadas, lo que demuestra la buena salud de un show que nunca es igual que el anterior y siempre sabe por donde salir para sorprenderte.<\/p>\n<p>Representada los domingos, viene genial si el d\u00eda 19 se trabaja y se prefiere algo durante el fin de semana. Se puede celebrar tanto el domingo 14 como el 21, de forma que toca decidir si celebrar el D\u00eda del Padre antes o despu\u00e9s de la fecha.<\/p>\n<p>Comprando la entrada en Oferplan cuesta solo 10\u20ac.<\/p>\n<p><strong>Direcci\u00f3n<\/strong>: <a href=\"https:\/\/teatroalfil.es\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Teatro Alfil<\/strong><\/a>. Calle del Pez, 10, 28004 Madrid<\/p>\n<p><strong>Metro<\/strong>: Tribunal (L\u00ednea 1), Noviciado (L\u00ednea 2) y Callao (L\u00ednea 3 y 5)<\/p>\n<p><strong>Autob\u00fas<\/strong>: 002 (gratuito), 3 y 147<\/p>\n<h2><a href=\"https:\/\/oferplan.abc.es\/ofertas-descuentos\/entradas-suenos-seductor-madrid-7752.html?utm_source=blog&amp;utm_medium=lacolmena&amp;utm_campaign=diapadre\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Sue\u00f1os de un seductor en el Teatro Lara<\/strong><\/a><\/h2>\n<p>Tambi\u00e9n en el <strong>Teatro Lara<\/strong> tenemos otra <strong>obra de teatro para el D\u00eda del Padre 2021<\/strong> imperdible. Por supuesto, estamos hablando de <strong>Sue\u00f1os de un seductor<\/strong>.<\/p>\n<p>Basada en la popular comedia de <strong>Woody Allen<\/strong> del a\u00f1o 1972, la traducci\u00f3n ha sido realizada por <strong>Juan Jos\u00e9 de Arteche<\/strong>, que tambi\u00e9n firma la versi\u00f3n junto a <strong>Ram\u00f3n Paso<\/strong>, el director de la obra.<\/p>\n<p>En cuanto a los protagonistas, Paso trabaja con <strong>Javier Mart\u00edn<\/strong> y <strong>Ana Azor\u00edn<\/strong>, acompa\u00f1ados a su vez de <strong>Carlos Segu\u00ed<\/strong>, <strong>In\u00e9s Kerz\u00e1n<\/strong> y <strong>\u00c1ngela Peirat<\/strong>.<\/p>\n<p>La obra nos traslada al divorcio de <strong>Allan Fix<\/strong>, que es apoyado y respaldado por una pareja de amigos. Sin embargo, durante el apoyo de esta pareja, Allan descubrir\u00e1 que sus sentimientos hacia Linda, la mujer de su amigo se ven incrementando.<\/p>\n<p>Entonces se encontrar\u00e1 en una posici\u00f3n imposible. Dejarse llevar por sus sentimientos y seducir a la mujer de su mejor amigo o ser fr\u00edo y olvidar esos sentimientos, priorizando el apoyo que su amigo le est\u00e1 brindando en estos dif\u00edciles momentos.<\/p>\n<p>Con el humor caracter\u00edstico de las obras de Woody Allen adaptado al gusto espa\u00f1ol, se trata de una obra muy divertida e interesante para pasar un D\u00eda del Padre a caracajadas.<\/p>\n<p>Puedes verla el 19 de marzo a las 20:15 en la Sala Lola Membrives del Teatro Lara. Con Oferplan, con un 33% de descuento.<\/p>\n<p><strong>Direcci\u00f3n<\/strong>: <a href=\"https:\/\/www.teatrolara.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Teatro Lara<\/strong><\/a>. Corredera Baja de San Pablo, 15, 28004 Madrid<\/p>\n<p><strong>Metro<\/strong>: Callao (L\u00edneas 3 y 5) y Santo Domingo (L\u00ednea 2)<\/p>\n<p><strong>Autob\u00fas<\/strong>: 001, 002 (gratuitos), 1, 2, 46, 74, 146, N16, N18, N19, N20, N21<\/p>\n<h2><a href=\"https:\/\/oferplan.abc.es\/ofertas-descuentos\/entradas-burundanga-madrid-7449.html?utm_source=blog&amp;utm_medium=lacolmena&amp;utm_campaign=diapadre\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Burundanga en el Teatro Maravillas<\/strong><\/a><\/h2>\n<p><iframe loading=\"lazy\" title=\"BURUNDANGA 11\u00ba Temporada en el Teatro Maravillas\" width=\"629\" height=\"354\" src=\"https:\/\/www.youtube.com\/embed\/-FgCuLpnXfQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><strong>Burundanga<\/strong> es probablemente una de las obras de teatro de mayor \u00e9xito que se hayan estrenado en Madrid a lo largo de toda la historia. Con once temporadas a sus espaldas, logr\u00f3 estar 72 meses consecutivos con todas las entradas vendidas, un hito al alcance de muy pocas producciones.<\/p>\n<p>La obra est\u00e1 escrita por <strong>Jordi Galcer\u00e1n<\/strong>, el tambi\u00e9n autor de <strong>El M\u00e9todo Gr\u00f6nholm<\/strong>, la obra espa\u00f1ola que m\u00e1s \u00e9xito ha tenido a nivel internacional en la \u00faltima d\u00e9cada, con versi\u00f3n cinematogr\u00e1fica incluida. En este caso, la obra est\u00e1 dirigida por <strong>Gabriel Olivares<\/strong>.<\/p>\n<p>De una hora y media de duraci\u00f3n, Burundanga est\u00e1 protagonizada por dos casting diferentes que se van alternando, algo normal despu\u00e9s de tantos a\u00f1os de \u00e9xito. Por un lado tenemos un reparto formado por <strong>Eloy Arenas, Ra\u00fal Pe\u00f1a, Rebeka Brik, Mar Abascal y Fran Nortes<\/strong>, mientras que a veces se alternan con <strong>Bart Santana, Guillermo Sanju\u00e1n, Andr\u00e9s Acevedo y Rebeca Plaza<\/strong>.<\/p>\n<p>La trama nos lleva al interior de un domicilio, donde se haya una chica con su mejor amiga. La chica descubre que se ha quedado embarazada y c\u00f3mo no estaba en sus planes se pregunta c\u00f3mo comentarlo a su chico.<\/p>\n<p>Su amiga le da una gran idea: usar burundanga, la droga de la verdad y del olvido, para saber qu\u00e9 piensa su pareja de su embarazo y as\u00ed saber c\u00f3mo actuar posteriormente seg\u00fan la reacci\u00f3n que tenga el chico.<\/p>\n<p>Curiosamente, cuando la droga hace efecto, la protagonista se encuentra con que el embarazo es el menor de sus problemas y aparecen otros nuevos como un nuevo compa\u00f1ero de piso, un comando terrorista y muchos otros enredos de los que no ten\u00eda la menor idea.<\/p>\n<p>Al final, la obra ofrece grandes carcajadas a la vez que muestra que incluso las personas m\u00e1s cercanas a nosotros pueden guardarnos grandes secretos.<\/p>\n<p>Una opci\u00f3n estupenda con una gran trayectoria de \u00e9xito para pasar una noche divertida en el teatro por el D\u00eda del Padre con un 30% de descuento con Oferplan.<\/p>\n<p><strong>Direcci\u00f3n<\/strong>: <a href=\"https:\/\/www.teatromaravillas.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Teatro Maravillas<\/strong><\/a>. Calle de Manuela Malasa\u00f1a, 6, 28004 Madrid<\/p>\n<p><strong>Autob\u00fas<\/strong>: 3, 21, 37, 40, 147 y 149<\/p>\n<p><strong>Metro<\/strong>: Bilbao (L\u00ednea 1 y 4)<\/p>\n<h2><a href=\"https:\/\/oferplan.abc.es\/ofertas-descuentos\/entradas-cadiz-madrid-7751.html?utm_source=blog&amp;utm_medium=lacolmena&amp;utm_campaign=diapadre\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>C\u00e1diz en el Teatro Lara<\/strong><\/a><\/h2>\n<p><iframe loading=\"lazy\" title=\"Teaser comedia &#039;C\u00e1diz&#039; del Teatro Lara\" width=\"629\" height=\"472\" src=\"https:\/\/www.youtube.com\/embed\/9Ud1Xe3GoQI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Otra obra ideal para el <strong>D\u00eda del Padre 2021<\/strong> es<strong> C\u00e1diz<\/strong>, que se vuelve a representar en el <strong>Teatro Lara<\/strong> en esta temporada, en este caso pasando a la sala principal debido al gran \u00e9xito de su \u00faltima temporada antes de la pandemia.<\/p>\n<p>Dirigida por <strong>Gabriel Olivares<\/strong>, que tambi\u00e9n dirige <strong>Burundanga<\/strong>, est\u00e1 escrita y protagonizada por <strong>Fran Nortes<\/strong>, al que tambi\u00e9n podemos ver en la obra anterior, as\u00ed como <strong>Bart Santana<\/strong> (otro actor de Burundanga) o <strong>Arturo Vegas<\/strong>, seg\u00fan la funci\u00f3n, acompa\u00f1ados de <strong>Nacho L\u00f3pez<\/strong>.<\/p>\n<p>En la obra, nos encontramos con tres amigos que llevan tiempo sin verse y que para retomar el tiempo perdido deciden hacer un viaje a <strong>C\u00e1diz<\/strong>, una de las mejores ciudades del mundo.<\/p>\n<p>Siendo de estos amigos que terminan consider\u00e1ndose la propia familia, a pesar de la distancia y los diferentes momentos vitales, la obra nos lleva a c\u00f3mo viven esto y, sobre todo, los cambios que han tenido en su vida adulta, no siendo ya tan parecidos como lo eran hasta entonces.<\/p>\n<p>De hecho, cada personaje tiene una forma de afrontar la vida, habiendo uno que prefiere vivir en el pasado y en los recuerdos, otro obsesionado con el futuro que vendr\u00e1 y un \u00faltimo amigo que prefiere vivir el momento en cada instante.<\/p>\n<p>Con una duraci\u00f3n de 90 minutos, puedes disfrutar de un 40% de descuento con Oferplan para la funci\u00f3n de este 19 de marzo.<\/p>\n<p><strong>Direcci\u00f3n:<\/strong> Teatro Lara. Corredera Baja de San Pablo, 15, 28004 Madrid<\/p>\n<p><strong>Metro<\/strong>: Callao (L\u00edneas 3 y 5) y Santo Domingo (L\u00ednea 2)<\/p>\n<p><strong>Autob\u00fas<\/strong>: 001, 002 (gratuitos), 1, 2, 46, 74, 146, N16, N18, N19, N20, N21<\/p>\n<p>Y si no te ha convencido ninguna de las obras, siempre puedes elegir un regalo original y pr\u00e1ctico: <a href=\"https:\/\/oferplan.abc.es\/blog\/eventos\/regalos-dia-del-padre-ideas-originales-para-todos-los-gustos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Regalos D\u00eda del Padre<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buscar obras de teatro para el d\u00eda del Padre de este 2021 es muy buena manera de celebrarlo. En un momento en el que siguen activas muchas restricciones, el teatro ha demostrado que la cultura es segura, permitiendo disfrutar de un rato de ocio con todas las medidas de seguridad. A\u00f1adi\u00e9ndole que el pr\u00f3ximo 19 [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":2511,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"\/blog\/wp-json\/wp\/v2\/posts\/2478"}],"collection":[{"href":"\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/comments?post=2478"}],"version-history":[{"count":3,"href":"\/blog\/wp-json\/wp\/v2\/posts\/2478\/revisions"}],"predecessor-version":[{"id":2514,"href":"\/blog\/wp-json\/wp\/v2\/posts\/2478\/revisions\/2514"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/media\/2511"}],"wp:attachment":[{"href":"\/blog\/wp-json\/wp\/v2\/media?parent=2478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/categories?post=2478"},{"taxonomy":"post_tag","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/tags?post=2478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}